{"id":11439,"date":"2023-01-26T13:28:59","date_gmt":"2023-01-26T06:28:59","guid":{"rendered":"https:\/\/www.kenan-asia.org\/kenanpartners\/"},"modified":"2023-01-26T13:28:59","modified_gmt":"2023-01-26T06:28:59","slug":"kenanpartners","status":"publish","type":"blog","link":"https:\/\/kenan-asia.org\/th\/blog\/kenanpartners\/","title":{"rendered":"\u201c\u0e04\u0e35\u0e19\u0e31\u0e19\u201d \u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e07\u0e32\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e01\u0e23\u0e40\u0e01\u0e37\u0e2d\u0e1a 2.9 \u0e41\u0e2a\u0e19\u0e04\u0e19\u0e43\u0e19\u0e1b\u0e35 2559"},"content":{"rendered":"<div id=\"pl-8210\"  class=\"panel-layout\" >\n<div id=\"pg-8210-0\"  class=\"panel-grid panel-no-style\"  data-style=\"{&quot;background_display&quot;:&quot;tile&quot;,&quot;cell_alignment&quot;:&quot;flex-start&quot;}\" >\n<div id=\"pgc-8210-0-0\"  class=\"panel-grid-cell\"  data-weight=\"0.5\" >\n<div id=\"panel-8210-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" data-style=\"{&quot;background_display&quot;:&quot;tile&quot;}\" >\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e04\u0e35\u0e19\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 (\u0e04\u0e35\u0e19\u0e31\u0e19) \u0e19\u0e33\u0e42\u0e14\u0e22\u0e04\u0e38\u0e13\u0e2b\u0e0d\u0e34\u0e07\u0e0a\u0e0e\u0e32 \u0e27\u0e31\u0e12\u0e19\u0e28\u0e34\u0e23\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e04\u0e35\u0e19\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 \u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23 \u0e17\u0e35\u0e48\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e02\u0e2d\u0e07\u0e04\u0e35\u0e19\u0e31\u0e19\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e40\u0e01\u0e37\u0e2d\u0e1a 290,000 \u0e04\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e1b\u0e35 2559 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04\u0e41\u0e25\u0e30\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e27\u0e34\u0e20\u0e32\u0e04\u0e41\u0e25\u0e30\u0e1e\u0e2b\u0e38\u0e20\u0e32\u0e04\u0e35\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21 \u0e13 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e40\u0e23\u0e40\u0e19\u0e0b\u0e2d\u0e07\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e23\u0e32\u0e0a\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e47\u0e27\u0e46 \u0e19\u0e35\u0e49<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"pgc-8210-0-1\"  class=\"panel-grid-cell\"  data-weight=\"0.5\" >\n<div id=\"panel-8210-0-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\" >\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-6247 aligncenter\" src=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Kenan-Praises-Partners-1.jpg\" sizes=\"(max-width: 760px) 100vw, 760px\" srcset=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Kenan-Praises-Partners-1.jpg 760w, https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Kenan-Praises-Partners-1-300x146.jpg 300w\" alt=\"\" width=\"760\" height=\"371\"><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"pg-8210-1\"  class=\"panel-grid panel-no-style\"  data-style=\"{&quot;background_display&quot;:&quot;tile&quot;,&quot;cell_alignment&quot;:&quot;flex-start&quot;}\" >\n<div id=\"pgc-8210-1-0\"  class=\"panel-grid-cell\"  data-style=\"{&quot;background_display&quot;:&quot;tile&quot;,&quot;vertical_alignment&quot;:&quot;auto&quot;}\"  data-weight=\"1\" >\n<div id=\"panel-8210-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"2\" data-style=\"{&quot;background_display&quot;:&quot;tile&quot;}\" >\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p><img decoding=\"async\" class=\"alignleft size-full wp-image-6250\" src=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Kenan-Praises-Partners-2.png\" alt=\"\" width=\"178\" height=\"256\" \/>\u0e13\u0e2b\u0e0d\u0e34\u0e07\u0e0a\u0e0e\u0e32\u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e02\u0e2d\u0e07\u0e04\u0e35\u0e19\u0e31\u0e19\u0e43\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e27\u0e48\u0e32 \u0e04\u0e35\u0e19\u0e31\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19\u0e01\u0e27\u0e48\u0e32 20 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e40\u0e01\u0e37\u0e2d\u0e1a 290,000 \u0e04\u0e19 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e17\u0e31\u0e49\u0e07\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e21\u0e2d\u0e35 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 225 \u0e04\u0e23\u0e31\u0e49\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 31 \u0e0a\u0e34\u0e49\u0e19 \u0e08\u0e31\u0e14\u0e04\u0e48\u0e32\u0e22\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 15 \u0e04\u0e23\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e38\u0e21\u0e0a\u0e19 79 \u0e04\u0e23\u0e31\u0e49\u0e07 \u201c\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e33\u0e21\u0e31\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e35\u0e19\u0e31\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e40\u0e0a\u0e34\u0e07\u0e1a\u0e27\u0e01\u0e41\u0e25\u0e30\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u201d \u0e04\u0e38\u0e13\u0e2b\u0e0d\u0e34\u0e07\u0e0a\u0e0e\u0e32\u0e01\u0e25\u0e48\u0e32\u0e27\u0e2a\u0e23\u0e38\u0e1b<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"pg-8210-2\"  class=\"panel-grid panel-no-style\"  data-style=\"{&quot;background_image_attachment&quot;:false,&quot;background_display&quot;:&quot;tile&quot;,&quot;cell_alignment&quot;:&quot;flex-start&quot;}\" >\n<div id=\"pgc-8210-2-0\"  class=\"panel-grid-cell\"  data-weight=\"1\" >\n<div id=\"panel-8210-2-0-0\" class=\"so-panel widget widget_gallery panel-first-child\" data-index=\"3\" data-style=\"{&#34;class&#34;:&#34;no-pagination&#34;,&#34;background_image_attachment&#34;:false,&#34;background_display&#34;:&#34;tile&#34;}\" >\n<div class=\"no-pagination panel-widget-style panel-widget-style-for-8210-2-0-0\" >\n<div class=\"thim-widget-gallery thim-widget-gallery-base\">\n<div class=\"thim-gallery source-images\" id=\"gallery_5959ff736765e\" data-per_page=\"6\">\n<div class=\"gallery-wrapper\">\n<div class=\"items row\" id=\"gallery_5959ff736765e_items\">\n<div class=\"item col-xs-6 col-md-4\">\n<div class=\"inner\">\t\t\t<a class=\"media\" href=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Partners2.png\" data-title=\"Partners2\" data-caption=\"\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Partners2.png\" alt=\"Partners2\"\/>\t\t\t<\/a>\t\t\t<\/p>\n<div class=\"infos\">\n<div class=\"title\">Partners2<\/div>\n<div class=\"caption\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"item col-xs-6 col-md-4\">\n<div class=\"inner\">\t\t\t<a class=\"media\" href=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Partners3.png\" data-title=\"Partners3\" data-caption=\"\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Partners3.png\" alt=\"Partners3\"\/>\t\t\t<\/a>\t\t\t<\/p>\n<div class=\"infos\">\n<div class=\"title\">Partners3<\/div>\n<div class=\"caption\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"item col-xs-6 col-md-4\">\n<div class=\"inner\">\t\t\t<a class=\"media\" href=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Partners4.png\" data-title=\"Partners4\" data-caption=\"\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Partners4.png\" alt=\"Partners4\"\/>\t\t\t<\/a>\t\t\t<\/p>\n<div class=\"infos\">\n<div class=\"title\">Partners4<\/div>\n<div class=\"caption\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"item col-xs-6 col-md-4\">\n<div class=\"inner\">\t\t\t<a class=\"media\" href=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Partners5.png\" data-title=\"Partners5\" data-caption=\"\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Partners5.png\" alt=\"Partners5\"\/>\t\t\t<\/a>\t\t\t<\/p>\n<div class=\"infos\">\n<div class=\"title\">Partners5<\/div>\n<div class=\"caption\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"item col-xs-6 col-md-4\">\n<div class=\"inner\">\t\t\t<a class=\"media\" href=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Partners6.png\" data-title=\"Partners6\" data-caption=\"\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Partners6.png\" alt=\"Partners6\"\/>\t\t\t<\/a>\t\t\t<\/p>\n<div class=\"infos\">\n<div class=\"title\">Partners6<\/div>\n<div class=\"caption\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"item col-xs-6 col-md-4\">\n<div class=\"inner\">\t\t\t<a class=\"media\" href=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Partners7.png\" data-title=\"Partners7\" data-caption=\"\">\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.kenan-asia.org\/\/wp-content\/uploads\/2017\/06\/Partners7.png\" alt=\"Partners7\"\/>\t\t\t<\/a>\t\t\t<\/p>\n<div class=\"infos\">\n<div class=\"title\">Partners7<\/div>\n<div class=\"caption\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div><\/div>\n<div class=\"gallery-pagination\">\n<div class=\"inner-nav\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"panel-8210-2-0-1\" class=\"so-panel widget widget_sow-editor\" data-index=\"4\" data-style=\"{&quot;background_display&quot;:&quot;tile&quot;}\" >\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d<br \/>\n\u0e2a\u0e38\u0e23\u0e31\u0e15\u0e19\u0e4c\u0e27\u0e14\u0e35 \u0e2a\u0e32\u0e22\u0e17\u0e2d\u0e07<br \/>\n\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e04\u0e35\u0e19\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22<br \/>\n\u0e42\u0e17\u0e23. 02 229 3131 \u0e15\u0e48\u0e2d 305 \u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d 086 606 6643<br \/>\n\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e4c <span id=\"cloaka6f1bfe3b0a485d61f5cf539e1f92a59\"><a href=\"mailto:suratvadees@kenan-asia.org?subject=Kenan%20partners\">suratvadees@kenan-asia.org<\/a><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"panel-8210-2-0-2\" class=\"so-panel widget widget_mc4wp_form_widget panel-last-child\" data-index=\"5\" data-style=\"{&quot;background_display&quot;:&quot;tile&quot;}\" >\n<h3 class=\"widget-title\">Subscribe to our monthly newsletter<\/h3>\n<p><!-- MailChimp for WordPress v4.1.2 - https:\/\/wordpress.org\/plugins\/mailchimp-for-wp\/ --><\/p>\n<form id=\"mc4wp-form-1\" class=\"mc4wp-form mc4wp-form-74\" method=\"post\" data-id=\"74\" data-name=\"Subscribe\" >\n<div class=\"mc4wp-form-fields\"><input type=\"email\" name=\"EMAIL\" placeholder=\"Email Address\" required><br \/>\n<button type=\"submit\"><i class=\"fa fa-chevron-circle-right\"><\/i><\/button><\/p>\n<div style=\"display: none;\"><input type=\"text\" name=\"_mc4wp_honeypot\" value=\"\" tabindex=\"-1\" autocomplete=\"off\" \/><\/div>\n<p><input type=\"hidden\" name=\"_mc4wp_timestamp\" value=\"1499070323\" \/><input type=\"hidden\" name=\"_mc4wp_form_id\" value=\"74\" \/><input type=\"hidden\" name=\"_mc4wp_form_element_id\" value=\"mc4wp-form-1\" \/><\/div>\n<div class=\"mc4wp-response\"><\/div>\n<\/form>\n<p><!-- \/ MailChimp for WordPress Plugin --><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e04\u0e35\u0e19\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 (\u0e04\u0e35\u0e19\u0e31\u0e19) \u0e19\u0e33\u0e42\u0e14\u0e22\u0e04\u0e38\u0e13\u0e2b\u0e0d\u0e34\u0e07\u0e0a\u0e0e\u0e32 \u0e27\u0e31\u0e12\u0e19\u0e28\u0e34\u0e23\u0e34 [&hellip;]<\/p>\n","protected":false},"featured_media":11440,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-categories":[261],"class_list":["post-11439","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog-categories-blog-th"],"acf":[],"_links":{"self":[{"href":"https:\/\/kenan-asia.org\/th\/wp-json\/wp\/v2\/blog\/11439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kenan-asia.org\/th\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/kenan-asia.org\/th\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/kenan-asia.org\/th\/wp-json\/wp\/v2\/blog\/11439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kenan-asia.org\/th\/wp-json\/wp\/v2\/media\/11440"}],"wp:attachment":[{"href":"https:\/\/kenan-asia.org\/th\/wp-json\/wp\/v2\/media?parent=11439"}],"wp:term":[{"taxonomy":"blog-categories","embeddable":true,"href":"https:\/\/kenan-asia.org\/th\/wp-json\/wp\/v2\/blog-categories?post=11439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}